{"id":70,"count":1,"description":"","link":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/","name":"Slider Home Aktuelles 1","slug":"slider-home-aktuelles-1-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Slider Home Aktuelles 1 Archive - Thierry Pr\u00e4zisionslackiertechnik GmbH Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slider Home Aktuelles 1 Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Thierry Pr\u00e4zisionslackiertechnik GmbH Germany\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/category\\\/slider-home-aktuelles-1-en\\\/\",\"url\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/category\\\/slider-home-aktuelles-1-en\\\/\",\"name\":\"Slider Home Aktuelles 1 Archive - Thierry Pr\u00e4zisionslackiertechnik GmbH Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/category\\\/slider-home-aktuelles-1-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/category\\\/slider-home-aktuelles-1-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slider Home Aktuelles 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/\",\"name\":\"Thierry Pr\u00e4zisionslackiertechnik GmbH Germany\",\"description\":\"Your professional partner for Master Sample Management, Color Standards, Test Agents and Equipment, Precision Color Cards, Painting Technology &amp; Measurements.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thierry-gmbh.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slider Home Aktuelles 1 Archive - Thierry Pr\u00e4zisionslackiertechnik GmbH Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/","og_locale":"en_US","og_type":"article","og_title":"Slider Home Aktuelles 1 Archive","og_url":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/","og_site_name":"Thierry Pr\u00e4zisionslackiertechnik GmbH Germany","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/","url":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/","name":"Slider Home Aktuelles 1 Archive - Thierry Pr\u00e4zisionslackiertechnik GmbH Germany","isPartOf":{"@id":"https:\/\/thierry-gmbh.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thierry-gmbh.de\/en\/category\/slider-home-aktuelles-1-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/thierry-gmbh.de\/en\/"},{"@type":"ListItem","position":2,"name":"Slider Home Aktuelles 1"}]},{"@type":"WebSite","@id":"https:\/\/thierry-gmbh.de\/en\/#website","url":"https:\/\/thierry-gmbh.de\/en\/","name":"Thierry Pr\u00e4zisionslackiertechnik GmbH Germany","description":"Your professional partner for Master Sample Management, Color Standards, Test Agents and Equipment, Precision Color Cards, Painting Technology &amp; Measurements.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thierry-gmbh.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/thierry-gmbh.de\/en\/wp-json\/wp\/v2\/categories\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thierry-gmbh.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/thierry-gmbh.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/thierry-gmbh.de\/en\/wp-json\/wp\/v2\/posts?categories=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}